{"id":3543,"date":"2021-04-29T10:40:40","date_gmt":"2021-04-29T15:40:40","guid":{"rendered":"http:\/\/www.seoultradingusa.com\/?page_id=3543"},"modified":"2021-04-29T14:27:52","modified_gmt":"2021-04-29T19:27:52","slug":"oseries-cn","status":"publish","type":"page","link":"http:\/\/www.seoultradingusa.com\/index.php\/oseries-cn\/","title":{"rendered":"O!series-cn"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3543\" class=\"elementor elementor-3543\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d822bf4 elementor-section-height-min-height elementor-section-items-bottom elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-invisible\" data-id=\"6d822bf4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:&quot;2492&quot;,&quot;url&quot;:&quot;http:\\\/\\\/www.seoultradingusa.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1.jpg&quot;},{&quot;id&quot;:2499,&quot;url&quot;:&quot;http:\\\/\\\/www.seoultradingusa.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2-2.jpg&quot;},{&quot;id&quot;:2500,&quot;url&quot;:&quot;http:\\\/\\\/www.seoultradingusa.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2-3.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:3000,&quot;background_slideshow_transition_duration&quot;:2000,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5e3da8d3\" data-id=\"5e3da8d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-254d3b32 elementor-hidden-phone elementor-view-default de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"254d3b32\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-624a308 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"624a308\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-279b4011\" data-id=\"279b4011\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3a7923fe elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a7923fe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-37c3d9ef\" data-id=\"37c3d9ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21544549 de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"21544549\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O!SERIES<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f8c43de de_scroll_animation_no elementor-widget elementor-widget-image\" data-id=\"7f8c43de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/elementor\/thumbs\/1-0622-p2c31gu0bu2tcxzb0p61nt5ziczdsn7vfosh1y9exc.png\" title=\"1-06(22)\" alt=\"1-06(22)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a8ceb61 de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3a8ceb61\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u54e6\uff01\u7cfb\u5217<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42d4fdc2 elementor-widget-divider--view-line de_scroll_animation_no elementor-widget elementor-widget-divider\" data-id=\"42d4fdc2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dda8ba8 de_scroll_animation_no elementor-widget elementor-widget-image\" data-id=\"dda8ba8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"289\" height=\"288\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/1-06.png\" class=\"attachment-full size-full wp-image-2501\" alt=\"\" srcset=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/1-06.png 289w, http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/1-06-150x150.png 150w\" sizes=\"(max-width: 289px) 100vw, 289px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38b4f8df de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"38b4f8df\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tO\uff01GRAIN\uff08\u8c37\u7269\uff09\u4e3a\u7528\u6237\u9910\u684c\u63d0\u4f9b\u6709\u673a\u519c\u548c\u73af\u4fdd\u8c37\u7269\u3002 <p>\u540c\u65f6\uff0c O\uff01NOODLE\u662f\u5f15\u9886\u65b0\u9c9c\u800c\u73b0\u4ee3\u5316\u5bb6\u5e38\u9762\u6761\u7684\u9886\u5148\u54c1\u724c\u3002\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1eab275 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1eab275\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22eb8cc\" data-id=\"22eb8cc\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-570349c de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"570349c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u5ba3\u4f20\u89c6\u9891<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f52f90 de_scroll_animation_no elementor-widget elementor-widget-video\" data-id=\"6f52f90\" data-element_type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/03\/mong_oserise.mp4\" controls=\"\" preload=\"metadata\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1961782e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1961782e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1501afcf\" data-id=\"1501afcf\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d8f749b elementor-arrows-position-outside de_scroll_animation_no elementor-widget elementor-widget-image-carousel\" data-id=\"2d8f749b\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-1.png\" alt=\"Asset-1.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-3.png\" alt=\"Asset-3.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-6.png\" alt=\"Asset-6.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-7.png\" alt=\"Asset-7.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-14.png\" alt=\"Asset-14.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-10.png\" alt=\"Asset-10.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-5.png\" alt=\"Asset-5.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-4.png\" alt=\"Asset-4.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-12.png\" alt=\"Asset-12.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-13.png\" alt=\"Asset-13.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-8.png\" alt=\"Asset-8.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-9.png\" alt=\"Asset-9.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-11.png\" alt=\"Asset-11.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-15.png\" alt=\"Asset-15.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-16.png\" alt=\"Asset-16.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-17.png\" alt=\"Asset-17.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/Asset-18.png\" alt=\"Asset-18.png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/1510133779623_1.jpg\" alt=\"1510133779623_1.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/1510133790892_1.jpg\" alt=\"1510133790892_1.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/1510133817607_1.jpg\" alt=\"1510133817607_1.jpg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/01\/151013380765_1.jpg\" alt=\"151013380765_1.jpg\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8250460 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8250460\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8dea334\" data-id=\"8dea334\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:2489,&quot;url&quot;:&quot;http:\\\/\\\/www.seoultradingusa.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/\\ub9cc\\ub450\\uc2dc\\ub9ac\\uc988-2.jpg&quot;},{&quot;id&quot;:2490,&quot;url&quot;:&quot;http:\\\/\\\/www.seoultradingusa.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Dai_\\ud638\\ub5a1\\ub2e8\\uccb42_-1.jpg&quot;},{&quot;id&quot;:2491,&quot;url&quot;:&quot;http:\\\/\\\/www.seoultradingusa.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/\\ud0d5\\uc2dc\\ub9ac\\uc988.jpg&quot;},{&quot;id&quot;:2492,&quot;url&quot;:&quot;http:\\\/\\\/www.seoultradingusa.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/1.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:3000,&quot;background_slideshow_slide_transition&quot;:&quot;slide_right&quot;,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e177b3d de_scroll_animation_no elementor-widget elementor-widget-spacer\" data-id=\"e177b3d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40c3f65\" data-id=\"40c3f65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e4ef99 de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"6e4ef99\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>LATEST UPDATE<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82e74d5 de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"82e74d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u4ea7\u54c1\u76ee\u5f55\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86923ed de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"86923ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\u9996\u5c14\u8d38\u6613\u516c\u53f8\u4e0d\u4ec5\u6d41\u901a\u81ea\u5df1\u54c1\u724c\u4ea7\u54c1\uff0c\u800c\u4e14\u8fd8\u6d41\u901a\u5168\u7403\u5176\u4ed6\u516c\u53f8\u76844,000\u591a\u79cd\u4ea7\u54c1\u3002\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07c97a0 elementor-align-left de_scroll_animation_no elementor-widget elementor-widget-button\" data-id=\"07c97a0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"http:\/\/www.seoultradingusa.com\/index.php\/product-catalog-cn\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u4ea7\u54c1\u76ee\u5f55<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O!SERIES \u54e6\uff01\u7cfb\u5217 O\uff01GRAIN\uff08\u8c37\u7269\uff09\u4e3a\u7528\u6237\u9910\u684c\u63d0\u4f9b\u6709\u673a\u519c\u548c\u73af\u4fdd\u8c37\u7269\u3002 \u540c\u65f6\uff0c O\uff01NOODLE\u662f\u5f15\u9886\u65b0\u9c9c\u800c\u73b0\u4ee3\u5316\u5bb6\u5e38\u9762\u6761\u7684\u9886\u5148\u54c1\u724c\u3002 \u5ba3\u4f20\u89c6\u9891 http:\/\/www.seoultradingusa.com\/wp-content\/uploads\/2021\/03\/mong_oserise.mp4 Previous Next LATEST UPDATE \u4ea7\u54c1\u76ee\u5f55\u9996\u5c14\u8d38\u6613\u516c\u53f8\u4e0d\u4ec5\u6d41\u901a\u81ea\u5df1\u54c1\u724c\u4ea7\u54c1\uff0c\u800c\u4e14\u8fd8\u6d41\u901a\u5168\u7403\u5176\u4ed6\u516c\u53f8\u76844,000\u591a\u79cd\u4ea7\u54c1\u3002 \u4ea7\u54c1\u76ee\u5f55<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_front_end_style_editor":"no","ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"off","ocean_display_footer_bottom":"off","ocean_custom_footer_template":"0"},"_links":{"self":[{"href":"http:\/\/www.seoultradingusa.com\/index.php\/wp-json\/wp\/v2\/pages\/3543"}],"collection":[{"href":"http:\/\/www.seoultradingusa.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.seoultradingusa.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.seoultradingusa.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.seoultradingusa.com\/index.php\/wp-json\/wp\/v2\/comments?post=3543"}],"version-history":[{"count":7,"href":"http:\/\/www.seoultradingusa.com\/index.php\/wp-json\/wp\/v2\/pages\/3543\/revisions"}],"predecessor-version":[{"id":3788,"href":"http:\/\/www.seoultradingusa.com\/index.php\/wp-json\/wp\/v2\/pages\/3543\/revisions\/3788"}],"wp:attachment":[{"href":"http:\/\/www.seoultradingusa.com\/index.php\/wp-json\/wp\/v2\/media?parent=3543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}